{"id":6875,"date":"2025-06-23T12:10:35","date_gmt":"2025-06-23T12:10:35","guid":{"rendered":"https:\/\/scooterandbikerental.com\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/"},"modified":"2025-06-23T15:32:56","modified_gmt":"2025-06-23T15:32:56","slug":"quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne","status":"publish","type":"post","link":"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/","title":{"rendered":"Quel permis faut-il pour conduire une moto de 125cc en Espagne ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se d\u00e9placer \u00e0 moto en ville ou sur une \u00eele comme Gran Canaria pr\u00e9sente de nombreux avantages : on \u00e9vite les embouteillages, on se gare facilement et on profite du trajet avec une libert\u00e9 difficile \u00e0 \u00e9galer. Mais avant de monter sur un scooter ou une moto l\u00e9g\u00e8re de 125cc, une question importante se pose :<strong> quel permis faut-il vraiment ?<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La bonne nouvelle, c\u2019est que si tu as d\u00e9j\u00e0 le permis voiture (<strong>le permis B<\/strong>), tu es peut-\u00eatre plus proche du but que tu ne le penses. Mais attention : il existe des conditions, des exceptions et des d\u00e9tails juridiques qu\u2019il vaut mieux conna\u00eetre. On t\u2019explique tout ici, sans d\u00e9tour, \u00e0 jour et avec des exemples concrets. Et \u00e0 la fin, on te montre comment louer l\u2019un de ces deux-roues sans prise de t\u00eate, que tu pr\u00e9voies une escapade ou que tu veuilles simplement te d\u00e9placer sur l\u2019\u00eele.   <\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Conditions_generales_pour_conduire_une_moto_de_125cc_en_Espagne\" >Conditions g\u00e9n\u00e9rales pour conduire une moto de 125cc en Espagne<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Que_dit_la_DGT_a_propos_du_permis_requis\" >Que dit la DGT \u00e0 propos du permis requis ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Differences_entre_les_permis_A1_A2_et_B\" >Diff\u00e9rences entre les permis A1, A2 et B<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Puis-je_conduire_une_moto_de_125cc_avec_le_permis_B_voiture\" >Puis-je conduire une moto de 125cc avec le permis B (voiture) ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Conditions_de_validite\" >Conditions de validit\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Anciennete_minimale_du_permis_B\" >Anciennet\u00e9 minimale du permis B<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Types_de_motos_autorisees_avec_le_permis_B\" >Types de motos autoris\u00e9es avec le permis B<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Conditions_pour_les_touristes_et_les_etrangers_en_Espagne\" >Conditions pour les touristes et les \u00e9trangers en Espagne<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Peut-on_conduire_avec_un_permis_etranger\" >Peut-on conduire avec un permis \u00e9tranger ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Permis_valables_dans_lUE_et_en_dehors_de_lUE\" >Permis valables dans l\u2019UE et en dehors de l\u2019UE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Cas_ou_un_permis_international_est_necessaire\" >Cas o\u00f9 un permis international est n\u00e9cessaire<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Quel_type_de_scooter_peut-on_louer_avec_chaque_permis\" >Quel type de scooter peut-on louer avec chaque permis<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Scooters_50cc_125cc_et_plus_de_%3E_125cc\" >Scooters 50cc, 125cc et plus de &gt; 125cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Conditions_legales_et_pratiques\" >Conditions l\u00e9gales et pratiques<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Que_se_passe-t-il_si_je_conduis_une_moto_sans_le_permis_adequat\" >Que se passe-t-il si je conduis une moto sans le permis ad\u00e9quat ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Amendes_et_sanctions\" >Amendes et sanctions<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Couverture_dassurance_et_responsabilite_legale\" >Couverture d\u2019assurance et responsabilit\u00e9 l\u00e9gale<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Conseils_avant_de_louer_une_moto_ou_un_scooter_en_Espagne\" >Conseils avant de louer une moto ou un scooter en Espagne<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Documents_necessaires\" >Documents n\u00e9cessaires<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Recommandations_de_securite\" >Recommandations de s\u00e9curit\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/scooterandbikerental.com\/fr\/blog\/quel-permis-faut-il-pour-conduire-une-moto-de-125cc-en-espagne\/#Ou_louer_un_scooter_a_Gran_Canaria\" >O\u00f9 louer un scooter \u00e0 Gran Canaria<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conditions_generales_pour_conduire_une_moto_de_125cc_en_Espagne\"><\/span><strong>Conditions g\u00e9n\u00e9rales pour conduire une moto de 125cc en Espagne<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_dit_la_DGT_a_propos_du_permis_requis\"><\/span><strong>Que dit la DGT \u00e0 propos du permis requis ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Direction G\u00e9n\u00e9rale de la Circulation (DGT) en Espagne indique que pour conduire une moto de 125cc, il faut poss\u00e9der un permis A1 ou, dans certains cas, un permis B. Ces motos sont consid\u00e9r\u00e9es comme des motocyclettes l\u00e9g\u00e8res, \u00e0 condition de ne pas d\u00e9passer 11\u202fkW de puissance (15\u202fCV) et un rapport puissance\/poids de 0,1\u202fkW\/kg.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Differences_entre_les_permis_A1_A2_et_B\"><\/span><strong>Diff\u00e9rences entre les permis A1, A2 et B<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Permis A1<\/strong> : Accessible d\u00e8s 16 ans. Permet de conduire des motos jusqu\u2019\u00e0 125cc. N\u00e9cessite un examen th\u00e9orique et pratique.  <\/li>\n\n\n\n<li><strong>Permis A2<\/strong> : \u00c0 partir de 18 ans. Autorise la conduite de motos de plus grosse cylindr\u00e9e, mais inclut aussi les 125cc. <\/li>\n\n\n\n<li><strong>Permis B <\/strong>: Le permis voiture. Il permet de conduire une moto de 125cc uniquement si tu le d\u00e9tiens depuis plus de 3 ans. Cette option <strong>n\u2019est valable qu\u2019en Espagne<\/strong>.  <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Puis-je_conduire_une_moto_de_125cc_avec_le_permis_B_voiture\"><\/span><strong>Puis-je conduire une moto de 125cc avec le permis B (voiture) ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, il est possible de conduire une moto de 125cc avec uniquement le permis voiture, <strong>mais pas dans tous les cas<\/strong>. Il existe des conditions pr\u00e9cises \u00e0 respecter, et toute personne titulaire du permis B ne peut pas automatiquement conduire une moto. <strong>L\u2019utilisation du permis B pour conduire une 125cc<\/strong> est autoris\u00e9e, mais cette r\u00e8gle ne s\u2019applique pas syst\u00e9matiquement.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conditions_de_validite\"><\/span><strong>Conditions de validit\u00e9<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le permis B ne permet de conduire une <strong>moto jusqu\u2019\u00e0 125cc <\/strong>que s\u2019il a \u00e9t\u00e9 d\u00e9livr\u00e9 par la Direction G\u00e9n\u00e9rale de la Circulation (DGT) en Espagne. De plus, le v\u00e9hicule doit respecter les <strong>limites fix\u00e9es pour le permis A1<\/strong> : ne pas d\u00e9passer 125cc, ni 11\u202fkW de puissance, et respecter le rapport puissance\/poids autoris\u00e9. Cette \u00e9quivalence <strong>n\u2019est valable qu\u2019en Espagne<\/strong> : si tu voyages dans un autre pays europ\u00e9en, elle ne s\u2019applique pas.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Anciennete_minimale_du_permis_B\"><\/span><strong>Anciennet\u00e9 minimale du permis B<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il est indispensable que le permis B ait au moins <strong>3 ans d\u2019anciennet\u00e9<\/strong>. Si tu viens de l\u2019obtenir, m\u00eame si tu as plus de 18 ans, <strong>tu n\u2019as pas le droit de conduire l\u00e9galement une moto de 125cc.<\/strong> <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Types_de_motos_autorisees_avec_le_permis_B\"><\/span><strong>Types de motos autoris\u00e9es avec le permis B<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tu ne peux conduire que des motos correspondant \u00e0 la cat\u00e9gorie A1 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Moto \u00e9lectrique 49cc<\/strong> (cyclomoteur) : tu peux \u00e9galement la conduire avec le permis AM.<\/li>\n\n\n\n<li><strong>Scooter 125cc \u00e9lectrique ou \u00e0 essence<\/strong>, \u00e0 condition qu\u2019il respecte les limites de puissance et de poids.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conditions_pour_les_touristes_et_les_etrangers_en_Espagne\"><\/span><strong>Conditions pour les touristes et les \u00e9trangers en Espagne<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conduire une moto de 125cc en Espagne ne concerne pas uniquement les r\u00e9sidents. De nombreux touristes et \u00e9trangers qui s\u00e9journent temporairement dans le pays envisagent aussi de louer une moto l\u00e9g\u00e8re pour se d\u00e9placer facilement. Dans ces cas-l\u00e0, <strong>le type de permis et sa validit\u00e9 l\u00e9gale peuvent varier<\/strong> consid\u00e9rablement selon le pays d\u2019origine du conducteur.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Peut-on_conduire_avec_un_permis_etranger\"><\/span><strong>Peut-on conduire avec un permis \u00e9tranger ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, c\u2019est possible. L\u2019Espagne autorise l\u2019utilisation de permis de conduire \u00e9trangers, \u00e0 condition qu\u2019ils soient en cours de validit\u00e9 et adapt\u00e9s au type de v\u00e9hicule concern\u00e9. Cependant, <strong>la reconnaissance n\u2019est pas automatique <\/strong>pour tout le monde. En g\u00e9n\u00e9ral, si ton permis provient d\u2019un pays de l\u2019Union europ\u00e9enne ou de l\u2019Espace \u00e9conomique europ\u00e9en, tu pourras conduire une moto de 125cc dans les m\u00eames conditions qu\u2019un citoyen espagnol. Aucune d\u00e9marche suppl\u00e9mentaire ni permis international ne sont n\u00e9cessaires.    <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Permis_valables_dans_lUE_et_en_dehors_de_lUE\"><\/span><strong>Permis valables dans l\u2019UE et en dehors de l\u2019UE<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Citoyens de l\u2019Union europ\u00e9enne ou de l\u2019Espace \u00e9conomique europ\u00e9en (EEE)<\/strong> : ils peuvent utiliser leur permis directement, sans d\u00e9marches suppl\u00e9mentaires.<\/li>\n\n\n\n<li><strong>Pays ayant un accord avec l\u2019Espagne<\/strong> (comme la Suisse, le Royaume-Uni, le Japon, entre autres) : le permis est g\u00e9n\u00e9ralement valable pour une dur\u00e9e d\u00e9termin\u00e9e.<\/li>\n\n\n\n<li><strong>Autres pays<\/strong> : tu auras besoin d\u2019un <strong>permis de conduire international<\/strong> traduit en espagnol, accompagn\u00e9 de ton permis original.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cas_ou_un_permis_international_est_necessaire\"><\/span><strong>Cas o\u00f9 un permis international est n\u00e9cessaire<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le permis international est un document compl\u00e9mentaire qui traduit ton permis original en plusieurs langues. Il est obligatoire <strong>si tu viens d\u2019un pays n\u2019ayant pas d\u2019accord avec l\u2019Espagne<\/strong> ou si ton permis est r\u00e9dig\u00e9 dans un <strong>autre alphabet<\/strong> (comme le cyrillique, l\u2019arabe ou le chinois). Il est \u00e9galement requis si tu pr\u00e9vois de rester en Espagne<strong> plus de six mois<\/strong>, car dans ce cas, tu devras entamer les d\u00e9marches pour \u00e9changer ton permis contre un permis espagnol, si la r\u00e9glementation le permet.  <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"446\" src=\"https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/Quel-permis-faut-il-pour-conduire-une-moto-125cc.webp\" alt=\"Quel permis faut-il pour conduire une moto 125cc\" class=\"wp-image-6879\" title=\"\" srcset=\"https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/Quel-permis-faut-il-pour-conduire-une-moto-125cc.webp 640w, https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/Quel-permis-faut-il-pour-conduire-une-moto-125cc-300x209.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Si tu viens de l\u2019\u00e9tranger, assure-toi que ton permis est valable en Espagne ou emporte avec toi un permis international.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quel_type_de_scooter_peut-on_louer_avec_chaque_permis\"><\/span><strong>Quel type de scooter peut-on louer avec chaque permis<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si tu envisages de louer une moto ou un scooter en Espagne, il est essentiel de savoir quel type de v\u00e9hicule tu peux conduire l\u00e9galement en fonction du permis que tu poss\u00e8des. M\u00eame si le terme \u00ab\u202fscooter\u202f\u00bb est utilis\u00e9 de mani\u00e8re g\u00e9n\u00e9rale, <strong>tous les mod\u00e8les ne sont pas identiques et ne n\u00e9cessitent pas le m\u00eame type de permis.<\/strong>  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scooters_50cc_125cc_et_plus_de_%3E_125cc\"><\/span><strong>Scooters 50cc, 125cc et plus de &gt; 125cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les <strong>scooters de 50cc<\/strong> sont les plus basiques. Ils sont consid\u00e9r\u00e9s comme des cyclomoteurs et leur vitesse est limit\u00e9e \u00e0 45\u202fkm\/h. Pour les conduire, il suffit d\u2019avoir le permis AM, accessible d\u00e8s l\u2019\u00e2ge de 15 ans.   <\/li>\n\n\n\n<li>En revanche, un <strong>scooter de 125cc <\/strong>entre d\u00e9j\u00e0 dans la cat\u00e9gorie des motos l\u00e9g\u00e8res. Le <strong>permis requis est g\u00e9n\u00e9ralement le permis A1<\/strong>, mais le permis B est \u00e9galement valable \u00e0 condition d\u2019avoir au moins trois ans d\u2019anciennet\u00e9. <\/li>\n\n\n\n<li>Les <strong>scooters de plus de 125cc<\/strong> \u2014 comme les mod\u00e8les de 300cc ou plus puissants \u2014 appartiennent \u00e0 une cat\u00e9gorie sup\u00e9rieure. Pour les conduire, il faut un permis A2 ou A, selon la puissance du v\u00e9hicule. <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conditions_legales_et_pratiques\"><\/span><strong>Conditions l\u00e9gales et pratiques<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En plus du <strong>permis requis pour louer un scooter<\/strong>, de nombreuses entreprises imposent des conditions suppl\u00e9mentaires li\u00e9es \u00e0 l\u2019\u00e2ge et \u00e0 l\u2019exp\u00e9rience. Dans la plupart des cas, <strong>il faut avoir au moins 21 ans pour louer <\/strong>un scooter de 125cc, bien que certaines compagnies acceptent les conducteurs de 18 ans titulaires du permis A1. Il est \u00e9galement n\u00e9cessaire de<strong> pr\u00e9senter le permis original<\/strong>, en cours de validit\u00e9, et parfois de justifier d\u2019une exp\u00e9rience pr\u00e9alable avec des motos, surtout pour les mod\u00e8les plus lourds ou avec vitesses manuelles. Si tu viens de <strong>l\u2019\u00e9tranger<\/strong>, assure-toi de remplir toutes les conditions l\u00e9gales avant de finaliser la r\u00e9servation. N\u2019oublie pas que le permis requis pour louer une moto en Espagne n\u2019est pas toujours le m\u00eame que celui pour la conduire : certaines entreprises appliquent leurs propres restrictions.    <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_se_passe-t-il_si_je_conduis_une_moto_sans_le_permis_adequat\"><\/span><strong>Que se passe-t-il si je conduis une moto sans le permis ad\u00e9quat ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cela peut sembler une infraction mineure, mais conduire sans le permis appropri\u00e9 entra\u00eene des sanctions importantes. Dans le cas des motos, ne pas avoir le bon permis peut co\u00fbter cher, m\u00eame s\u2019il s\u2019agit d\u2019une erreur par ignorance. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Amendes_et_sanctions\"><\/span><strong>Amendes et sanctions<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Amendes pouvant aller jusqu\u2019\u00e0 <strong>500 euros.<\/strong><\/li>\n\n\n\n<li>Retrait de points sur le permis.<\/li>\n\n\n\n<li>Immobilisation <strong>possible du v\u00e9hicule.<\/strong><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Couverture_dassurance_et_responsabilite_legale\"><\/span><strong>Couverture d\u2019assurance et responsabilit\u00e9 l\u00e9gale<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si tu conduis sans \u00eatre l\u00e9galement autoris\u00e9, <strong>l\u2019assurance ne couvrira pas les dommages.<\/strong><\/li>\n\n\n\n<li>En cas d\u2019accident, la responsabilit\u00e9 financi\u00e8re peut retomber sur toi.<\/li>\n\n\n\n<li>L\u2019entreprise de location peut \u00e9galement r\u00e9clamer des dommages si tu as menti sur ton permis.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conseils_avant_de_louer_une_moto_ou_un_scooter_en_Espagne\"><\/span><strong>Conseils avant de louer une moto ou un scooter en Espagne<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Documents_necessaires\"><\/span><strong>Documents n\u00e9cessaires<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Permis de conduire valide et en cours de validit\u00e9.<\/li>\n\n\n\n<li>DNI, pasaporte o NIE.<\/li>\n\n\n\n<li>Carte d\u2019identit\u00e9, passeport ou NIE.<\/li>\n\n\n\n<li>Dans certains cas, un permis international est requis si tu n\u2019es pas citoyen de l\u2019UE.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recommandations_de_securite\"><\/span><strong>Recommandations de s\u00e9curit\u00e9<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Porte toujours un casque homologu\u00e9.<\/li>\n\n\n\n<li>\u00c9vite de conduire si tu n\u2019as pas d\u2019exp\u00e9rience.<\/li>\n\n\n\n<li>Informe-toi sur les conditions d\u2019assurance de la location.<\/li>\n\n\n\n<li>Assure-toi de bien conna\u00eetre les r\u00e8gles de circulation locales.<br><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"446\" src=\"https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/permis-B-pour-moto-125cc.webp\" alt=\"permis B pour moto 125cc\" class=\"wp-image-6877\" title=\"\" srcset=\"https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/permis-B-pour-moto-125cc.webp 640w, https:\/\/scooterandbikerental.com\/wp-content\/uploads\/2025\/06\/permis-B-pour-moto-125cc-300x209.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Conduire sans le bon permis peut entra\u00eener des sanctions, et l\u2019assurance pourrait ne pas te couvrir.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ou_louer_un_scooter_a_Gran_Canaria\"><\/span><strong>O\u00f9 louer un scooter \u00e0 Gran Canaria<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Chez <a href=\"https:\/\/scooterandbikerental.com\/es\/\"><strong>Scooter and Bike Rental<\/strong><\/a>, tu trouveras des scooters et motos \u00e9lectriques de 50cc, 125cc et plus, tous r\u00e9vis\u00e9s et pr\u00eats \u00e0 parcourir l\u2019\u00eele. Le <strong>permis requis pour<\/strong> <a href=\"https:\/\/scooterandbikerental.com\/fr\/moto-scooter-125\/\"><strong>louer une moto<\/strong><\/a> d\u00e9pend du mod\u00e8le choisi et du respect des conditions l\u00e9gales et de l\u2019entreprise. Notre \u00e9quipe v\u00e9rifie ton permis et t\u2019aide \u00e0 choisir le mod\u00e8le adapt\u00e9 \u00e0 ton niveau d\u2019exp\u00e9rience et au type de trajet que tu souhaites faire.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gran Canaria se d\u00e9couvre mieux sur deux roues\u2026 mais toujours dans le respect de la loi !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se d\u00e9placer \u00e0 moto en ville ou sur une \u00eele comme Gran Canaria pr\u00e9sente de nombreux avantages : on \u00e9vite les embouteillages, on se gare facilement et on profite du trajet avec une libert\u00e9 difficile \u00e0 \u00e9galer. Mais avant de monter sur un scooter ou une moto l\u00e9g\u00e8re de 125cc, une question importante se pose [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-6875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/posts\/6875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/comments?post=6875"}],"version-history":[{"count":0,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/posts\/6875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/media\/6878"}],"wp:attachment":[{"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/media?parent=6875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/categories?post=6875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scooterandbikerental.com\/fr\/wp-json\/wp\/v2\/tags?post=6875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}